{"id":8,"date":"2023-05-11T09:30:44","date_gmt":"2023-05-11T12:30:44","guid":{"rendered":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/?page_id=8"},"modified":"2023-09-25T08:55:58","modified_gmt":"2023-09-25T11:55:58","slug":"sede","status":"publish","type":"page","link":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/","title":{"rendered":"Sede"},"content":{"rendered":"<p>El evento se desarrollar\u00e1 en el complejo acad\u00e9mico y cultural \u201cSergio Karakachoff\u201d que se encuentra en la zona c\u00e9ntrica de la ciudad de La Plata y pertenece a la Universidad Nacional de La Plata (UNLP).<\/p>\n<p>Direcci\u00f3n: calle 48 e\/ 6 y 7<\/p>\n<p>&nbsp;<\/p>\n<p>La cena de camarader\u00eda se realizar\u00e1 el<b>\u00a0jueves 5 de octubre a las 21 hs<\/b>\u00a0en el Sal\u00f3n Florencia<\/p>\n<p>Direcci\u00f3n: Diag. 73 N\u00ba 1555 e\/ 11 y 56<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento se desarrollar\u00e1 en el complejo acad\u00e9mico y cultural \u201cSergio Karakachoff\u201d que se encuentra en la zona c\u00e9ntrica de la ciudad de La Plata y pertenece a la Universidad Nacional de La Plata (UNLP). Direcci\u00f3n: calle 48 e\/ 6 y 7 &nbsp; La cena de camarader\u00eda se realizar\u00e1 el\u00a0jueves 5 de octubre a las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry","post"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El evento se desarrollar\u00e1 en el complejo acad\u00e9mico y cultural \u201cSergio Karakachoff\u201d que se encuentra en la zona c\u00e9ntrica de la ciudad de La Plata y pertenece a la Universidad Nacional de La Plata (UNLP). Direcci\u00f3n: calle 48 e\/ 6 y 7 La cena de camarader\u00eda se realizar\u00e1 el jueves 5 de octubre a las\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Ronco. Edici\u00f3n CINDECA de ORO -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sede - VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Ronco. Edici\u00f3n CINDECA de ORO\" \/>\n\t\t<meta property=\"og:description\" content=\"El evento se desarrollar\u00e1 en el complejo acad\u00e9mico y cultural \u201cSergio Karakachoff\u201d que se encuentra en la zona c\u00e9ntrica de la ciudad de La Plata y pertenece a la Universidad Nacional de La Plata (UNLP). Direcci\u00f3n: calle 48 e\/ 6 y 7 La cena de camarader\u00eda se realizar\u00e1 el jueves 5 de octubre a las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-05-11T12:30:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-09-25T11:55:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sede - VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Ronco. Edici\u00f3n CINDECA de ORO\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El evento se desarrollar\u00e1 en el complejo acad\u00e9mico y cultural \u201cSergio Karakachoff\u201d que se encuentra en la zona c\u00e9ntrica de la ciudad de La Plata y pertenece a la Universidad Nacional de La Plata (UNLP). Direcci\u00f3n: calle 48 e\/ 6 y 7 La cena de camarader\u00eda se realizar\u00e1 el jueves 5 de octubre a las\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/sede\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/sede\\\/#listItem\",\"name\":\"Sede\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/sede\\\/#listItem\",\"position\":2,\"name\":\"Sede\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/#organization\",\"name\":\"VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Tonco. Edici\\u00f3n CINDECA de ORO\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/sede\\\/#webpage\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/sede\\\/\",\"name\":\"Sede - VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Ronco. Edici\\u00f3n CINDECA de ORO\",\"description\":\"El evento se desarrollar\\u00e1 en el complejo acad\\u00e9mico y cultural \\u201cSergio Karakachoff\\u201d que se encuentra en la zona c\\u00e9ntrica de la ciudad de La Plata y pertenece a la Universidad Nacional de La Plata (UNLP). Direcci\\u00f3n: calle 48 e\\\/ 6 y 7 La cena de camarader\\u00eda se realizar\\u00e1 el jueves 5 de octubre a las\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/sede\\\/#breadcrumblist\"},\"datePublished\":\"2023-05-11T09:30:44-03:00\",\"dateModified\":\"2023-09-25T08:55:58-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/#website\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/\",\"name\":\"VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Tonco. Edici\\u00f3n CINDECA de ORO\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/viijca-cindecadeoro\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sede - VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Ronco. Edici\u00f3n CINDECA de ORO","description":"El evento se desarrollar\u00e1 en el complejo acad\u00e9mico y cultural \u201cSergio Karakachoff\u201d que se encuentra en la zona c\u00e9ntrica de la ciudad de La Plata y pertenece a la Universidad Nacional de La Plata (UNLP). Direcci\u00f3n: calle 48 e\/ 6 y 7 La cena de camarader\u00eda se realizar\u00e1 el jueves 5 de octubre a las","canonical_url":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro#listItem","position":1,"name":"Home","item":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro","nextItem":{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/#listItem","name":"Sede"}},{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/#listItem","position":2,"name":"Sede","previousItem":{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/#organization","name":"VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Tonco. Edici\u00f3n CINDECA de ORO","url":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/"},{"@type":"WebPage","@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/#webpage","url":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/","name":"Sede - VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Ronco. Edici\u00f3n CINDECA de ORO","description":"El evento se desarrollar\u00e1 en el complejo acad\u00e9mico y cultural \u201cSergio Karakachoff\u201d que se encuentra en la zona c\u00e9ntrica de la ciudad de La Plata y pertenece a la Universidad Nacional de La Plata (UNLP). Direcci\u00f3n: calle 48 e\/ 6 y 7 La cena de camarader\u00eda se realizar\u00e1 el jueves 5 de octubre a las","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/#website"},"breadcrumb":{"@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/#breadcrumblist"},"datePublished":"2023-05-11T09:30:44-03:00","dateModified":"2023-09-25T08:55:58-03:00"},{"@type":"WebSite","@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/#website","url":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/","name":"VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Tonco. Edici\u00f3n CINDECA de ORO","inLanguage":"es-AR","publisher":{"@id":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/#organization"}}]},"og:locale":"es_ES","og:site_name":"VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Ronco. Edici\u00f3n CINDECA de ORO -","og:type":"article","og:title":"Sede - VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Ronco. Edici\u00f3n CINDECA de ORO","og:description":"El evento se desarrollar\u00e1 en el complejo acad\u00e9mico y cultural \u201cSergio Karakachoff\u201d que se encuentra en la zona c\u00e9ntrica de la ciudad de La Plata y pertenece a la Universidad Nacional de La Plata (UNLP). Direcci\u00f3n: calle 48 e\/ 6 y 7 La cena de camarader\u00eda se realizar\u00e1 el jueves 5 de octubre a las","og:url":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/","article:published_time":"2023-05-11T12:30:44+00:00","article:modified_time":"2023-09-25T11:55:58+00:00","twitter:card":"summary_large_image","twitter:title":"Sede - VII Jornadas en Ciencias Aplicadas Dr. Jorge J. Ronco. Edici\u00f3n CINDECA de ORO","twitter:description":"El evento se desarrollar\u00e1 en el complejo acad\u00e9mico y cultural \u201cSergio Karakachoff\u201d que se encuentra en la zona c\u00e9ntrica de la ciudad de La Plata y pertenece a la Universidad Nacional de La Plata (UNLP). Direcci\u00f3n: calle 48 e\/ 6 y 7 La cena de camarader\u00eda se realizar\u00e1 el jueves 5 de octubre a las"},"aioseo_meta_data":{"post_id":"8","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-11 12:40:00","updated":"2025-06-13 16:17:09","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSede\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro"},{"label":"Sede","link":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/sede\/"}],"coauthors":[],"author_meta":{"author_link":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/author\/congresos\/","display_name":"congresos"},"relative_dates":{"created":"Posted 3 a\u00f1os ago","modified":"Updated 3 a\u00f1os ago"},"absolute_dates":{"created":"Posted on 11 mayo, 2023","modified":"Updated on 25 septiembre, 2023"},"absolute_dates_time":{"created":"Posted on 11 mayo, 2023 9:30 am","modified":"Updated on 25 septiembre, 2023 8:55 am"},"featured_img_caption":"","featured_img":false,"series_order":"","_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":0,"href":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"wp:attachment":[{"href":"https:\/\/congresos.unlp.edu.ar\/viijca-cindecadeoro\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}