{"id":295,"date":"2020-10-10T13:21:35","date_gmt":"2020-10-10T16:21:35","guid":{"rendered":"http:\/\/congresos.unlp.edu.ar\/simposio-fce\/?page_id=295"},"modified":"2026-06-29T19:37:39","modified_gmt":"2026-06-29T22:37:39","slug":"presentacion-de-trabajos","status":"publish","type":"page","link":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/","title":{"rendered":"ENVIO DE TRABAJOS"},"content":{"rendered":"<div id=\"pl-295\"  class=\"panel-layout\" ><div id=\"pg-295-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-295-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-295-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p>El Simposio invita a\u00a0 investigadores, docentes, estudiantes y profesionales a presentar trabajos vinculados con las distintas \u00e1reas de la investigaci\u00f3n contable. A trav\u00e9s de este espacio, se busca fomentar la producci\u00f3n y difusi\u00f3n del conocimiento, promover el intercambio de experiencias y contribuir al fortalecimiento de la investigaci\u00f3n contable en sus diversos campos de aplicaci\u00f3n de manera <strong>gratuita<\/strong>.<\/p>\n<p><em>Todos los autores del trabajo deber\u00e1n estar <a href=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/oyentes-en-el-evento\/\" target=\"_blank\" rel=\"noopener\">inscriptos<\/a> al evento.<\/em><\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-295-0-1\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-295-0-2\"  class=\"panel-grid-cell\" ><div id=\"panel-295-0-2-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"1\" ><a href=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/enviar-trabajo\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"152\" src=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/porfi-300x152.jpg\" class=\"image wp-image-2133  attachment-medium size-medium\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/porfi-300x152.jpg 300w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/porfi.jpg 477w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div><\/div><\/div><div id=\"pg-295-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-295-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-295-1-0-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"2\" ><a href=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/?p=1024\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"389\" src=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/ev-academica-vf.jpg\" class=\"image wp-image-2125  attachment-full size-full\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/ev-academica-vf.jpg 424w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/ev-academica-vf-300x275.jpg 300w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/><\/a><\/div><\/div><div id=\"pgc-295-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-295-1-1-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"3\" ><a href=\"https:\/\/sedici.unlp.edu.ar\/handle\/10915\/70739\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"452\" height=\"383\" src=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/issn-vf.jpg\" class=\"image wp-image-2124  attachment-full size-full\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/issn-vf.jpg 452w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/issn-vf-300x254.jpg 300w\" sizes=\"auto, (max-width: 452px) 100vw, 452px\" \/><\/a><\/div><\/div><div id=\"pgc-295-1-2\"  class=\"panel-grid-cell\" ><div id=\"panel-295-1-2-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"4\" ><img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"385\" src=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/expo-virtual-vf.jpg\" class=\"image wp-image-2123  attachment-full size-full\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/expo-virtual-vf.jpg 432w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/expo-virtual-vf-300x267.jpg 300w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/div><\/div><\/div><div id=\"pg-295-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-295-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-295-2-0-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"5\" ><a href=\"https:\/\/revistas.unlp.edu.ar\/proyecciones\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"2132\" height=\"494\" src=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/proyecciones.png\" class=\"image wp-image-2191  attachment-full size-full\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/proyecciones.png 2132w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/proyecciones-300x70.png 300w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/proyecciones-1024x237.png 1024w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/proyecciones-768x178.png 768w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/proyecciones-1536x356.png 1536w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2026\/06\/proyecciones-2048x475.png 2048w\" sizes=\"auto, (max-width: 2132px) 100vw, 2132px\" \/><\/a><\/div><\/div><\/div><div id=\"pg-295-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-295-3-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-295-3-1\"  class=\"panel-grid-cell\" ><div id=\"panel-295-3-1-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"6\" ><a href=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/?page_id=859&#038;preview=true\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/Temario-2-300x226.jpg\" class=\"image wp-image-819  attachment-medium size-medium\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/Temario-2-300x226.jpg 300w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/Temario-2-1024x773.jpg 1024w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/Temario-2-768x580.jpg 768w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/Temario-2.jpg 1426w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div><\/div><div id=\"pgc-295-3-2\"  class=\"panel-grid-cell panel-grid-cell-mobile-last\" ><div id=\"panel-295-3-2-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"7\" ><a href=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/?page_id=875&#038;preview=true\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"222\" src=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/Reglamento-300x222.jpg\" class=\"image wp-image-822  attachment-medium size-medium\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/Reglamento-300x222.jpg 300w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/Reglamento-1024x758.jpg 1024w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/Reglamento-768x569.jpg 768w, https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/Reglamento.jpg 1429w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div><\/div><div id=\"pgc-295-3-3\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El Simposio invita a\u00a0 investigadores, docentes, estudiantes y profesionales a presentar trabajos vinculados con las distintas \u00e1reas de la investigaci\u00f3n contable. A trav\u00e9s de este espacio, se busca fomentar la producci\u00f3n y difusi\u00f3n del conocimiento, promover el intercambio de experiencias y contribuir al fortalecimiento de la investigaci\u00f3n contable en sus diversos campos de aplicaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-295","page","type-page","status-publish","hentry","post"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Simposio invita a investigadores, docentes, estudiantes y profesionales a presentar trabajos vinculados con las distintas \u00e1reas de la investigaci\u00f3n contable. A trav\u00e9s de este espacio, se busca fomentar la producci\u00f3n y difusi\u00f3n del conocimiento, promover el intercambio de experiencias y contribuir al fortalecimiento de la investigaci\u00f3n contable en sus diversos campos de aplicaci\u00f3n de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Simposio de Investigaci\u00f3n Contable -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"ENVIO DE TRABAJOS - Simposio de Investigaci\u00f3n Contable\" \/>\n\t\t<meta property=\"og:description\" content=\"El Simposio invita a investigadores, docentes, estudiantes y profesionales a presentar trabajos vinculados con las distintas \u00e1reas de la investigaci\u00f3n contable. A trav\u00e9s de este espacio, se busca fomentar la producci\u00f3n y difusi\u00f3n del conocimiento, promover el intercambio de experiencias y contribuir al fortalecimiento de la investigaci\u00f3n contable en sus diversos campos de aplicaci\u00f3n de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/WhatsApp-Image-2021-09-14-at-13.11.49.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/WhatsApp-Image-2021-09-14-at-13.11.49.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"112\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-10-10T16:21:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-29T22:37:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"ENVIO DE TRABAJOS - Simposio de Investigaci\u00f3n Contable\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Simposio invita a investigadores, docentes, estudiantes y profesionales a presentar trabajos vinculados con las distintas \u00e1reas de la investigaci\u00f3n contable. A trav\u00e9s de este espacio, se busca fomentar la producci\u00f3n y difusi\u00f3n del conocimiento, promover el intercambio de experiencias y contribuir al fortalecimiento de la investigaci\u00f3n contable en sus diversos campos de aplicaci\u00f3n de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/WhatsApp-Image-2021-09-14-at-13.11.49.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/presentacion-de-trabajos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/presentacion-de-trabajos\\\/#listItem\",\"name\":\"ENVIO DE TRABAJOS\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/presentacion-de-trabajos\\\/#listItem\",\"position\":2,\"name\":\"ENVIO DE TRABAJOS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/#organization\",\"name\":\"17\\u00ba Simposio Regional de Investigaci\\u00f3n Contable\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/presentacion-de-trabajos\\\/#webpage\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/presentacion-de-trabajos\\\/\",\"name\":\"ENVIO DE TRABAJOS - Simposio de Investigaci\\u00f3n Contable\",\"description\":\"El Simposio invita a investigadores, docentes, estudiantes y profesionales a presentar trabajos vinculados con las distintas \\u00e1reas de la investigaci\\u00f3n contable. A trav\\u00e9s de este espacio, se busca fomentar la producci\\u00f3n y difusi\\u00f3n del conocimiento, promover el intercambio de experiencias y contribuir al fortalecimiento de la investigaci\\u00f3n contable en sus diversos campos de aplicaci\\u00f3n de\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/presentacion-de-trabajos\\\/#breadcrumblist\"},\"datePublished\":\"2020-10-10T13:21:35-03:00\",\"dateModified\":\"2026-06-29T19:37:39-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/#website\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/\",\"name\":\"18\\u00ba Simposio Regional de Investigaci\\u00f3n Contable\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/simposio-fce\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"ENVIO DE TRABAJOS - Simposio de Investigaci\u00f3n Contable","description":"El Simposio invita a investigadores, docentes, estudiantes y profesionales a presentar trabajos vinculados con las distintas \u00e1reas de la investigaci\u00f3n contable. A trav\u00e9s de este espacio, se busca fomentar la producci\u00f3n y difusi\u00f3n del conocimiento, promover el intercambio de experiencias y contribuir al fortalecimiento de la investigaci\u00f3n contable en sus diversos campos de aplicaci\u00f3n de","canonical_url":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce#listItem","position":1,"name":"Home","item":"https:\/\/congresos.unlp.edu.ar\/simposio-fce","nextItem":{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/#listItem","name":"ENVIO DE TRABAJOS"}},{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/#listItem","position":2,"name":"ENVIO DE TRABAJOS","previousItem":{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/#organization","name":"17\u00ba Simposio Regional de Investigaci\u00f3n Contable","url":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/"},{"@type":"WebPage","@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/#webpage","url":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/","name":"ENVIO DE TRABAJOS - Simposio de Investigaci\u00f3n Contable","description":"El Simposio invita a investigadores, docentes, estudiantes y profesionales a presentar trabajos vinculados con las distintas \u00e1reas de la investigaci\u00f3n contable. A trav\u00e9s de este espacio, se busca fomentar la producci\u00f3n y difusi\u00f3n del conocimiento, promover el intercambio de experiencias y contribuir al fortalecimiento de la investigaci\u00f3n contable en sus diversos campos de aplicaci\u00f3n de","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/#website"},"breadcrumb":{"@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/#breadcrumblist"},"datePublished":"2020-10-10T13:21:35-03:00","dateModified":"2026-06-29T19:37:39-03:00"},{"@type":"WebSite","@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/#website","url":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/","name":"18\u00ba Simposio Regional de Investigaci\u00f3n Contable","inLanguage":"es-AR","publisher":{"@id":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Simposio de Investigaci\u00f3n Contable -","og:type":"article","og:title":"ENVIO DE TRABAJOS - Simposio de Investigaci\u00f3n Contable","og:description":"El Simposio invita a investigadores, docentes, estudiantes y profesionales a presentar trabajos vinculados con las distintas \u00e1reas de la investigaci\u00f3n contable. A trav\u00e9s de este espacio, se busca fomentar la producci\u00f3n y difusi\u00f3n del conocimiento, promover el intercambio de experiencias y contribuir al fortalecimiento de la investigaci\u00f3n contable en sus diversos campos de aplicaci\u00f3n de","og:url":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/","og:image":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/WhatsApp-Image-2021-09-14-at-13.11.49.jpeg","og:image:secure_url":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/WhatsApp-Image-2021-09-14-at-13.11.49.jpeg","og:image:width":1280,"og:image:height":112,"article:published_time":"2020-10-10T16:21:35+00:00","article:modified_time":"2026-06-29T22:37:39+00:00","twitter:card":"summary","twitter:title":"ENVIO DE TRABAJOS - Simposio de Investigaci\u00f3n Contable","twitter:description":"El Simposio invita a investigadores, docentes, estudiantes y profesionales a presentar trabajos vinculados con las distintas \u00e1reas de la investigaci\u00f3n contable. A trav\u00e9s de este espacio, se busca fomentar la producci\u00f3n y difusi\u00f3n del conocimiento, promover el intercambio de experiencias y contribuir al fortalecimiento de la investigaci\u00f3n contable en sus diversos campos de aplicaci\u00f3n de","twitter:image":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-content\/uploads\/sites\/15\/2021\/09\/WhatsApp-Image-2021-09-14-at-13.11.49.jpeg"},"aioseo_meta_data":{"post_id":"295","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2022-07-23 13:57:18","updated":"2026-06-30 13:00:14","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/congresos.unlp.edu.ar\/simposio-fce\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tENVIO DE TRABAJOS\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/congresos.unlp.edu.ar\/simposio-fce"},{"label":"ENVIO DE TRABAJOS","link":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/presentacion-de-trabajos\/"}],"coauthors":[],"author_meta":{"author_link":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/author\/laplatasimposio\/","display_name":"laplatasimposio"},"relative_dates":{"created":"Posted 6 a\u00f1os ago","modified":"Updated 2 meses ago"},"absolute_dates":{"created":"Posted on 10 octubre, 2020","modified":"Updated on 29 junio, 2026"},"absolute_dates_time":{"created":"Posted on 10 octubre, 2020 1:21 pm","modified":"Updated on 29 junio, 2026 7:37 pm"},"featured_img_caption":"","featured_img":false,"series_order":"","_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-json\/wp\/v2\/pages\/295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-json\/wp\/v2\/comments?post=295"}],"version-history":[{"count":0,"href":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-json\/wp\/v2\/pages\/295\/revisions"}],"wp:attachment":[{"href":"https:\/\/congresos.unlp.edu.ar\/simposio-fce\/wp-json\/wp\/v2\/media?parent=295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}