{"id":1285,"count":1,"description":"","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/segregacion\/","name":"SEGREGACION","slug":"segregacion","taxonomy":"palabras_claves","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/segregacion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/palabras_claves\\\/1285\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/palabras_claves\\\/segregacion\\\/#listItem\",\"name\":\"SEGREGACION\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/palabras_claves\\\/segregacion\\\/#listItem\",\"position\":2,\"name\":\"SEGREGACION\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/palabras_claves\\\/1285\\\/#collectionpage\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/palabras_claves\\\/1285\\\/\",\"name\":\"SEGREGACION - Encuentro de Becaries de Posgrado de la UNLP\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/palabras_claves\\\/1285\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/#organization\",\"name\":\"Encuentro de Becaries de Posgrado de la UNLP\",\"description\":\"Otro sitio m\\u00e1s de Portal de Congresos de la UNLP Sitios\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/07\\\/cabezalEBEC2020_0-scaled.jpg\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/palabras_claves\\\/1285\\\/#organizationLogo\",\"width\":2560,\"height\":498,\"caption\":\"Encuentro de Becarios de la UNLP\"},\"image\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/palabras_claves\\\/1285\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/#website\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/\",\"name\":\"Encuentro de Becaries de Posgrado de la UNLP\",\"description\":\"Otro sitio m\\u00e1s de Portal de Congresos de la UNLP Sitios\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"SEGREGACION - Encuentro de Becaries de Posgrado de la UNLP","description":"","canonical_url":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/segregacion\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves\/1285\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020#listItem","position":1,"name":"Home","item":"https:\/\/congresos.unlp.edu.ar\/ebec2020","nextItem":{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/segregacion\/#listItem","name":"SEGREGACION"}},{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/segregacion\/#listItem","position":2,"name":"SEGREGACION","previousItem":{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves\/1285\/#collectionpage","url":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves\/1285\/","name":"SEGREGACION - Encuentro de Becaries de Posgrado de la UNLP","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/#website"},"breadcrumb":{"@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves\/1285\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/#organization","name":"Encuentro de Becaries de Posgrado de la UNLP","description":"Otro sitio m\u00e1s de Portal de Congresos de la UNLP Sitios","url":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/","logo":{"@type":"ImageObject","url":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-content\/uploads\/sites\/24\/2020\/07\/cabezalEBEC2020_0-scaled.jpg","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves\/1285\/#organizationLogo","width":2560,"height":498,"caption":"Encuentro de Becarios de la UNLP"},"image":{"@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves\/1285\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/#website","url":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/","name":"Encuentro de Becaries de Posgrado de la UNLP","description":"Otro sitio m\u00e1s de Portal de Congresos de la UNLP Sitios","inLanguage":"es-AR","publisher":{"@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSEGREGACION\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020"},{"label":"SEGREGACION","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/segregacion\/"}],"acf":[],"_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves\/1285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/taxonomies\/palabras_claves"}],"wp:post_type":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie?palabras_claves=1285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}