{"id":689,"count":1,"description":"","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/la-platas-paseo-del-bosque\/","name":"LA PLATA'S \"PASEO DEL BOSQUE\"","slug":"la-platas-paseo-del-bosque","taxonomy":"keywords","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords\/689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/taxonomies\/keywords"}],"wp:post_type":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie?keywords=689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}