{"id":1056,"count":1,"description":"","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/scorpion-detection\/","name":"Scorpion detection","slug":"scorpion-detection","taxonomy":"keywords","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/scorpion-detection\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/keywords\\\/1056\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/keywords\\\/scorpion-detection\\\/#listItem\",\"name\":\"Scorpion detection\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/keywords\\\/scorpion-detection\\\/#listItem\",\"position\":2,\"name\":\"Scorpion detection\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/keywords\\\/1056\\\/#collectionpage\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/keywords\\\/1056\\\/\",\"name\":\"Scorpion detection - Encuentro de Becaries de Posgrado de la UNLP\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/keywords\\\/1056\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/#organization\",\"name\":\"Encuentro de Becaries de Posgrado de la UNLP\",\"description\":\"Otro sitio m\\u00e1s de Portal de Congresos de la UNLP Sitios\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/07\\\/cabezalEBEC2020_0-scaled.jpg\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/keywords\\\/1056\\\/#organizationLogo\",\"width\":2560,\"height\":498,\"caption\":\"Encuentro de Becarios de la UNLP\"},\"image\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/wp-json\\\/wp\\\/v2\\\/keywords\\\/1056\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/#website\",\"url\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/\",\"name\":\"Encuentro de Becaries de Posgrado de la UNLP\",\"description\":\"Otro sitio m\\u00e1s de Portal de Congresos de la UNLP Sitios\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/congresos.unlp.edu.ar\\\/ebec2020\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Scorpion detection - Encuentro de Becaries de Posgrado de la UNLP","description":"","canonical_url":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/scorpion-detection\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords\/1056\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020#listItem","position":1,"name":"Home","item":"https:\/\/congresos.unlp.edu.ar\/ebec2020","nextItem":{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/scorpion-detection\/#listItem","name":"Scorpion detection"}},{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/scorpion-detection\/#listItem","position":2,"name":"Scorpion detection","previousItem":{"@type":"ListItem","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords\/1056\/#collectionpage","url":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords\/1056\/","name":"Scorpion detection - Encuentro de Becaries de Posgrado de la UNLP","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/#website"},"breadcrumb":{"@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords\/1056\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/#organization","name":"Encuentro de Becaries de Posgrado de la UNLP","description":"Otro sitio m\u00e1s de Portal de Congresos de la UNLP Sitios","url":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/","logo":{"@type":"ImageObject","url":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-content\/uploads\/sites\/24\/2020\/07\/cabezalEBEC2020_0-scaled.jpg","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords\/1056\/#organizationLogo","width":2560,"height":498,"caption":"Encuentro de Becarios de la UNLP"},"image":{"@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords\/1056\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/#website","url":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/","name":"Encuentro de Becaries de Posgrado de la UNLP","description":"Otro sitio m\u00e1s de Portal de Congresos de la UNLP Sitios","inLanguage":"en-US","publisher":{"@id":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tScorpion detection\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020"},{"label":"Scorpion detection","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/scorpion-detection\/"}],"acf":[],"_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords\/1056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/taxonomies\/keywords"}],"wp:post_type":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie?keywords=1056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}