{"id":5014,"date":"2020-11-05T22:47:38","date_gmt":"2020-11-06T01:47:38","guid":{"rendered":"http:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/ornella-andrea-moretto\/?lang=es"},"modified":"2020-11-11T00:30:44","modified_gmt":"2020-11-11T03:30:44","slug":"ornella-andrea-moretto","status":"publish","type":"becarie","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/ornella-andrea-moretto\/","title":{"rendered":"Ornella Andrea Moretto"},"author":2,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"palabras_claves":[1484,125,1485,1486],"keywords":[1487,131,1488,1489],"organismo_que_otorgo_la_beca":[34],"tipo_de_beca":[36],"unidad_academica":[38],"area_de_conocimiento":[39],"class_list":["post-5014","becarie","type-becarie","status-publish","hentry","palabras_claves-adultes","palabras_claves-educacion","palabras_claves-horticultores","palabras_claves-migrantes","keywords-adults","keywords-education","keywords-horticulturist","keywords-migrants","organismo_que_otorgo_la_beca-conicet","tipo_de_beca-doctoral","unidad_academica-facultad-de-humanidades-y-ciencias-de-la-educacion","area_de_conocimiento-cs-sociales","post"],"aioseo_notices":[],"acf":[],"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/author\/congresos\/","display_name":"congresos"},"relative_dates":{"created":"Posted 6 years ago","modified":"Updated 6 years ago"},"absolute_dates":{"created":"Posted on ","modified":"Updated on "},"absolute_dates_time":{"created":"Posted on  10:47 pm","modified":"Updated on  12:30 am"},"featured_img_caption":"","tax_additional":{"palabras_claves":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/adultes\/\" class=\"advgb-post-tax-term\">ADULTES<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/educacion\/\" class=\"advgb-post-tax-term\">EDUCACI\u00d3N<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/horticultores\/\" class=\"advgb-post-tax-term\">HORTICULTORES<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/migrantes\/\" class=\"advgb-post-tax-term\">MIGRANTES<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ADULTES<\/span>","<span class=\"advgb-post-tax-term\">EDUCACI\u00d3N<\/span>","<span class=\"advgb-post-tax-term\">HORTICULTORES<\/span>","<span class=\"advgb-post-tax-term\">MIGRANTES<\/span>"],"slug":"palabras_claves","name":"Palabras claves"},"keywords":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/adults\/\" class=\"advgb-post-tax-term\">ADULTS<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/education\/\" class=\"advgb-post-tax-term\">EDUCATION<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/horticulturist\/\" class=\"advgb-post-tax-term\">HORTICULTURIST<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/migrants\/\" class=\"advgb-post-tax-term\">MIGRANTS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ADULTS<\/span>","<span class=\"advgb-post-tax-term\">EDUCATION<\/span>","<span class=\"advgb-post-tax-term\">HORTICULTURIST<\/span>","<span class=\"advgb-post-tax-term\">MIGRANTS<\/span>"],"slug":"keywords","name":"Keywords"},"organismo_que_otorgo_la_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/organismo_que_otorgo_la_beca\/conicet\/\" class=\"advgb-post-tax-term\">CONICET<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">CONICET<\/span>"],"slug":"organismo_que_otorgo_la_beca","name":"Organismos que otorgan las becas"},"tipo_de_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/tipo_de_beca\/doctoral\/\" class=\"advgb-post-tax-term\">Doctoral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Doctoral<\/span>"],"slug":"tipo_de_beca","name":"Tipos de beca"},"unidad_academica":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/unidad_academica\/facultad-de-humanidades-y-ciencias-de-la-educacion\/\" class=\"advgb-post-tax-term\">FACULTAD DE HUMANIDADES Y CIENCIAS DE LA EDUCACI\u00d3N<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">FACULTAD DE HUMANIDADES Y CIENCIAS DE LA EDUCACI\u00d3N<\/span>"],"slug":"unidad_academica","name":"Unidades acad\u00e9micas"},"area_de_conocimiento":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/area_de_conocimiento\/cs-sociales\/\" class=\"advgb-post-tax-term\">Cs. Sociales<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Cs. Sociales<\/span>"],"slug":"area_de_conocimiento","name":"\u00c1reas de conocimiento"}},"series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie\/5014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/types\/becarie"}],"wp:attachment":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/media?parent=5014"}],"wp:term":[{"taxonomy":"palabras_claves","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves?post=5014"},{"taxonomy":"keywords","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords?post=5014"},{"taxonomy":"organismo_que_otorgo_la_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/organismo_que_otorgo_la_beca?post=5014"},{"taxonomy":"tipo_de_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/tipo_de_beca?post=5014"},{"taxonomy":"unidad_academica","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/unidad_academica?post=5014"},{"taxonomy":"area_de_conocimiento","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/area_de_conocimiento?post=5014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}