{"id":4041,"date":"2020-11-05T22:33:48","date_gmt":"2020-11-06T01:33:48","guid":{"rendered":"http:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/maria-elisa-helman\/?lang=es"},"modified":"2020-11-11T02:00:52","modified_gmt":"2020-11-11T05:00:52","slug":"maria-elisa-helman","status":"publish","type":"becarie","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/maria-elisa-helman\/","title":{"rendered":"Mar\u00eda Elisa Helman"},"author":2,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"palabras_claves":[576,1159,1160],"keywords":[580,1161,1162],"organismo_que_otorgo_la_beca":[34],"tipo_de_beca":[36],"unidad_academica":[59],"area_de_conocimiento":[60],"class_list":["post-4041","becarie","type-becarie","status-publish","hentry","palabras_claves-argentina","palabras_claves-sarcocystis-spp","palabras_claves-suinos","keywords-argentina","keywords-sarcocystis-spp","keywords-swine","organismo_que_otorgo_la_beca-conicet","tipo_de_beca-doctoral","unidad_academica-facultad-de-ciencias-veterinarias","area_de_conocimiento-veterinaria","post"],"aioseo_notices":[],"acf":[],"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/author\/congresos\/","display_name":"congresos"},"relative_dates":{"created":"Posted 6 years ago","modified":"Updated 6 years ago"},"absolute_dates":{"created":"Posted on ","modified":"Updated on "},"absolute_dates_time":{"created":"Posted on  10:33 pm","modified":"Updated on  2:00 am"},"featured_img_caption":"","tax_additional":{"palabras_claves":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/argentina\/\" class=\"advgb-post-tax-term\">ARGENTINA<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/sarcocystis-spp\/\" class=\"advgb-post-tax-term\">SARCOCYSTIS SPP<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/suinos\/\" class=\"advgb-post-tax-term\">SUINOS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ARGENTINA<\/span>","<span class=\"advgb-post-tax-term\">SARCOCYSTIS SPP<\/span>","<span class=\"advgb-post-tax-term\">SUINOS<\/span>"],"slug":"palabras_claves","name":"Palabras claves"},"keywords":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/argentina\/\" class=\"advgb-post-tax-term\">ARGENTINA<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/sarcocystis-spp\/\" class=\"advgb-post-tax-term\">SARCOCYSTIS SPP<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/swine\/\" class=\"advgb-post-tax-term\">SWINE<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ARGENTINA<\/span>","<span class=\"advgb-post-tax-term\">SARCOCYSTIS SPP<\/span>","<span class=\"advgb-post-tax-term\">SWINE<\/span>"],"slug":"keywords","name":"Keywords"},"organismo_que_otorgo_la_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/organismo_que_otorgo_la_beca\/conicet\/\" class=\"advgb-post-tax-term\">CONICET<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">CONICET<\/span>"],"slug":"organismo_que_otorgo_la_beca","name":"Organismos que otorgan las becas"},"tipo_de_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/tipo_de_beca\/doctoral\/\" class=\"advgb-post-tax-term\">Doctoral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Doctoral<\/span>"],"slug":"tipo_de_beca","name":"Tipos de beca"},"unidad_academica":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/unidad_academica\/facultad-de-ciencias-veterinarias\/\" class=\"advgb-post-tax-term\">FACULTAD DE CIENCIAS VETERINARIAS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">FACULTAD DE CIENCIAS VETERINARIAS<\/span>"],"slug":"unidad_academica","name":"Unidades acad\u00e9micas"},"area_de_conocimiento":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/area_de_conocimiento\/veterinaria\/\" class=\"advgb-post-tax-term\">Veterinaria<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Veterinaria<\/span>"],"slug":"area_de_conocimiento","name":"\u00c1reas de conocimiento"}},"series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie\/4041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/types\/becarie"}],"wp:attachment":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/media?parent=4041"}],"wp:term":[{"taxonomy":"palabras_claves","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves?post=4041"},{"taxonomy":"keywords","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords?post=4041"},{"taxonomy":"organismo_que_otorgo_la_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/organismo_que_otorgo_la_beca?post=4041"},{"taxonomy":"tipo_de_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/tipo_de_beca?post=4041"},{"taxonomy":"unidad_academica","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/unidad_academica?post=4041"},{"taxonomy":"area_de_conocimiento","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/area_de_conocimiento?post=4041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}