{"id":4029,"date":"2020-11-05T22:32:56","date_gmt":"2020-11-06T01:32:56","guid":{"rendered":"http:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/mariela-grisolia-romero\/?lang=es"},"modified":"2020-11-11T08:22:57","modified_gmt":"2020-11-11T11:22:57","slug":"mariela-grisolia-romero","status":"publish","type":"becarie","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/mariela-grisolia-romero\/","title":{"rendered":"Mariela Grisolia Romero"},"author":2,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"palabras_claves":[1136,1135,1133,1137,1134],"keywords":[1140,1138,1141,1142,1139],"organismo_que_otorgo_la_beca":[34],"tipo_de_beca":[36],"unidad_academica":[59],"area_de_conocimiento":[60],"class_list":["post-4029","becarie","type-becarie","status-publish","hentry","palabras_claves-analogo-de-gnrh","palabras_claves-contracepcion","palabras_claves-felino","palabras_claves-gonadas","palabras_claves-testiculo","keywords-contraception","keywords-feline","keywords-gnrh-analog","keywords-gonad","keywords-testicle","organismo_que_otorgo_la_beca-conicet","tipo_de_beca-doctoral","unidad_academica-facultad-de-ciencias-veterinarias","area_de_conocimiento-veterinaria","post"],"aioseo_notices":[],"acf":[],"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/author\/congresos\/","display_name":"congresos"},"relative_dates":{"created":"Posted 6 years ago","modified":"Updated 6 years ago"},"absolute_dates":{"created":"Posted on ","modified":"Updated on "},"absolute_dates_time":{"created":"Posted on  10:32 pm","modified":"Updated on  8:22 am"},"featured_img_caption":"","tax_additional":{"palabras_claves":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/analogo-de-gnrh\/\" class=\"advgb-post-tax-term\">AN\u00c1LOGO DE GNRH<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/contracepcion\/\" class=\"advgb-post-tax-term\">CONTRACEPCI\u00d3N<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/felino\/\" class=\"advgb-post-tax-term\">FELINO<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/gonadas\/\" class=\"advgb-post-tax-term\">G\u00d3NADAS<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/testiculo\/\" class=\"advgb-post-tax-term\">TEST\u00cdCULO<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">AN\u00c1LOGO DE GNRH<\/span>","<span class=\"advgb-post-tax-term\">CONTRACEPCI\u00d3N<\/span>","<span class=\"advgb-post-tax-term\">FELINO<\/span>","<span class=\"advgb-post-tax-term\">G\u00d3NADAS<\/span>","<span class=\"advgb-post-tax-term\">TEST\u00cdCULO<\/span>"],"slug":"palabras_claves","name":"Palabras claves"},"keywords":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/contraception\/\" class=\"advgb-post-tax-term\">CONTRACEPTION<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/feline\/\" class=\"advgb-post-tax-term\">FELINE<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/gnrh-analog\/\" class=\"advgb-post-tax-term\">GNRH ANALOG<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/gonad\/\" class=\"advgb-post-tax-term\">GONAD<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/testicle\/\" class=\"advgb-post-tax-term\">TESTICLE<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">CONTRACEPTION<\/span>","<span class=\"advgb-post-tax-term\">FELINE<\/span>","<span class=\"advgb-post-tax-term\">GNRH ANALOG<\/span>","<span class=\"advgb-post-tax-term\">GONAD<\/span>","<span class=\"advgb-post-tax-term\">TESTICLE<\/span>"],"slug":"keywords","name":"Keywords"},"organismo_que_otorgo_la_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/organismo_que_otorgo_la_beca\/conicet\/\" class=\"advgb-post-tax-term\">CONICET<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">CONICET<\/span>"],"slug":"organismo_que_otorgo_la_beca","name":"Organismos que otorgan las becas"},"tipo_de_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/tipo_de_beca\/doctoral\/\" class=\"advgb-post-tax-term\">Doctoral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Doctoral<\/span>"],"slug":"tipo_de_beca","name":"Tipos de beca"},"unidad_academica":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/unidad_academica\/facultad-de-ciencias-veterinarias\/\" class=\"advgb-post-tax-term\">FACULTAD DE CIENCIAS VETERINARIAS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">FACULTAD DE CIENCIAS VETERINARIAS<\/span>"],"slug":"unidad_academica","name":"Unidades acad\u00e9micas"},"area_de_conocimiento":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/area_de_conocimiento\/veterinaria\/\" class=\"advgb-post-tax-term\">Veterinaria<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Veterinaria<\/span>"],"slug":"area_de_conocimiento","name":"\u00c1reas de conocimiento"}},"series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie\/4029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/types\/becarie"}],"wp:attachment":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/media?parent=4029"}],"wp:term":[{"taxonomy":"palabras_claves","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves?post=4029"},{"taxonomy":"keywords","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords?post=4029"},{"taxonomy":"organismo_que_otorgo_la_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/organismo_que_otorgo_la_beca?post=4029"},{"taxonomy":"tipo_de_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/tipo_de_beca?post=4029"},{"taxonomy":"unidad_academica","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/unidad_academica?post=4029"},{"taxonomy":"area_de_conocimiento","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/area_de_conocimiento?post=4029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}