{"id":3077,"date":"2020-11-05T22:28:14","date_gmt":"2020-11-06T01:28:14","guid":{"rendered":"http:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/martin-nicolas-gatti\/?lang=es"},"modified":"2020-11-11T16:32:17","modified_gmt":"2020-11-11T19:32:17","slug":"martin-nicolas-gatti","status":"publish","type":"becarie","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/martin-nicolas-gatti\/","title":{"rendered":"Martin Nicol\u00e1s Gatti"},"author":2,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"palabras_claves":[1018,1021,1019,1020],"keywords":[1022,1023,1024,1025],"organismo_que_otorgo_la_beca":[34],"tipo_de_beca":[153],"unidad_academica":[294],"area_de_conocimiento":[541],"class_list":["post-3077","becarie","type-becarie","status-publish","hentry","palabras_claves-1-propanol","palabras_claves-catalizadores-de-niquel","palabras_claves-glicerol-crudo","palabras_claves-hidrogenolisis","keywords-1-propanol","keywords-crude-glycerol","keywords-hydrogenolysis","keywords-nickel-catalysts","organismo_que_otorgo_la_beca-conicet","tipo_de_beca-posdoctoral","unidad_academica-facultad-de-ingenieria","area_de_conocimiento-ingenieria","post"],"aioseo_notices":[],"acf":[],"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/author\/congresos\/","display_name":"congresos"},"relative_dates":{"created":"Posted 6 years ago","modified":"Updated 6 years ago"},"absolute_dates":{"created":"Posted on ","modified":"Updated on "},"absolute_dates_time":{"created":"Posted on  10:28 pm","modified":"Updated on  4:32 pm"},"featured_img_caption":"","tax_additional":{"palabras_claves":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/1-propanol\/\" class=\"advgb-post-tax-term\">1-PROPANOL<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/catalizadores-de-niquel\/\" class=\"advgb-post-tax-term\">CATALIZADORES DE N\u00cdQUEL<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/glicerol-crudo\/\" class=\"advgb-post-tax-term\">GLICEROL CRUDO<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/hidrogenolisis\/\" class=\"advgb-post-tax-term\">HIDROGEN\u00d3LISIS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">1-PROPANOL<\/span>","<span class=\"advgb-post-tax-term\">CATALIZADORES DE N\u00cdQUEL<\/span>","<span class=\"advgb-post-tax-term\">GLICEROL CRUDO<\/span>","<span class=\"advgb-post-tax-term\">HIDROGEN\u00d3LISIS<\/span>"],"slug":"palabras_claves","name":"Palabras claves"},"keywords":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/1-propanol\/\" class=\"advgb-post-tax-term\">1-PROPANOL<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/crude-glycerol\/\" class=\"advgb-post-tax-term\">CRUDE GLYCEROL<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/hydrogenolysis\/\" class=\"advgb-post-tax-term\">HYDROGENOLYSIS<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/nickel-catalysts\/\" class=\"advgb-post-tax-term\">NICKEL CATALYSTS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">1-PROPANOL<\/span>","<span class=\"advgb-post-tax-term\">CRUDE GLYCEROL<\/span>","<span class=\"advgb-post-tax-term\">HYDROGENOLYSIS<\/span>","<span class=\"advgb-post-tax-term\">NICKEL CATALYSTS<\/span>"],"slug":"keywords","name":"Keywords"},"organismo_que_otorgo_la_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/organismo_que_otorgo_la_beca\/conicet\/\" class=\"advgb-post-tax-term\">CONICET<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">CONICET<\/span>"],"slug":"organismo_que_otorgo_la_beca","name":"Organismos que otorgan las becas"},"tipo_de_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/tipo_de_beca\/posdoctoral\/\" class=\"advgb-post-tax-term\">Posdoctoral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Posdoctoral<\/span>"],"slug":"tipo_de_beca","name":"Tipos de beca"},"unidad_academica":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/unidad_academica\/facultad-de-ingenieria\/\" class=\"advgb-post-tax-term\">FACULTAD DE INGENIER\u00cdA<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">FACULTAD DE INGENIER\u00cdA<\/span>"],"slug":"unidad_academica","name":"Unidades acad\u00e9micas"},"area_de_conocimiento":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/area_de_conocimiento\/ingenieria\/\" class=\"advgb-post-tax-term\">Ingenier\u00eda<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Ingenier\u00eda<\/span>"],"slug":"area_de_conocimiento","name":"\u00c1reas de conocimiento"}},"series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie\/3077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/types\/becarie"}],"wp:attachment":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/media?parent=3077"}],"wp:term":[{"taxonomy":"palabras_claves","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves?post=3077"},{"taxonomy":"keywords","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords?post=3077"},{"taxonomy":"organismo_que_otorgo_la_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/organismo_que_otorgo_la_beca?post=3077"},{"taxonomy":"tipo_de_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/tipo_de_beca?post=3077"},{"taxonomy":"unidad_academica","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/unidad_academica?post=3077"},{"taxonomy":"area_de_conocimiento","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/area_de_conocimiento?post=3077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}