{"id":2556,"date":"2020-11-05T22:18:40","date_gmt":"2020-11-06T01:18:40","guid":{"rendered":"http:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/florencia-debora-dosil-hiriart\/?lang=es"},"modified":"2020-11-11T18:40:06","modified_gmt":"2020-11-11T21:40:06","slug":"florencia-debora-dosil-hiriart","status":"publish","type":"becarie","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/florencia-debora-dosil-hiriart\/","title":{"rendered":"Florencia D\u00e9bora Dosil Hiriart"},"author":8,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"palabras_claves":[787,790,789,788],"keywords":[791,794,793,792],"organismo_que_otorgo_la_beca":[34],"tipo_de_beca":[36],"unidad_academica":[35],"area_de_conocimiento":[37],"class_list":["post-2556","becarie","type-becarie","status-publish","hentry","palabras_claves-adenostemma","palabras_claves-biogeografia","palabras_claves-filogenia","palabras_claves-taxonomia","keywords-adenostemma","keywords-biogeography","keywords-phylogeny","keywords-taxonomy","organismo_que_otorgo_la_beca-conicet","tipo_de_beca-doctoral","unidad_academica-facultad-de-ciencias-naturales-y-museo","area_de_conocimiento-cs-agricolas-y-biologicas","post"],"aioseo_notices":[],"acf":[],"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/author\/ezemanzur\/","display_name":"ezemanzur"},"relative_dates":{"created":"Posted 6 years ago","modified":"Updated 6 years ago"},"absolute_dates":{"created":"Posted on ","modified":"Updated on "},"absolute_dates_time":{"created":"Posted on  10:18 pm","modified":"Updated on  6:40 pm"},"featured_img_caption":"","tax_additional":{"palabras_claves":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/adenostemma\/\" class=\"advgb-post-tax-term\">ADENOSTEMMA<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/biogeografia\/\" class=\"advgb-post-tax-term\">BIOGEOGRAF\u00cdA<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/filogenia\/\" class=\"advgb-post-tax-term\">FILOGENIA<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/taxonomia\/\" class=\"advgb-post-tax-term\">TAXONOM\u00cdA<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ADENOSTEMMA<\/span>","<span class=\"advgb-post-tax-term\">BIOGEOGRAF\u00cdA<\/span>","<span class=\"advgb-post-tax-term\">FILOGENIA<\/span>","<span class=\"advgb-post-tax-term\">TAXONOM\u00cdA<\/span>"],"slug":"palabras_claves","name":"Palabras claves"},"keywords":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/adenostemma\/\" class=\"advgb-post-tax-term\">ADENOSTEMMA<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/biogeography\/\" class=\"advgb-post-tax-term\">BIOGEOGRAPHY<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/phylogeny\/\" class=\"advgb-post-tax-term\">PHYLOGENY<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/taxonomy\/\" class=\"advgb-post-tax-term\">TAXONOMY<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">ADENOSTEMMA<\/span>","<span class=\"advgb-post-tax-term\">BIOGEOGRAPHY<\/span>","<span class=\"advgb-post-tax-term\">PHYLOGENY<\/span>","<span class=\"advgb-post-tax-term\">TAXONOMY<\/span>"],"slug":"keywords","name":"Keywords"},"organismo_que_otorgo_la_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/organismo_que_otorgo_la_beca\/conicet\/\" class=\"advgb-post-tax-term\">CONICET<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">CONICET<\/span>"],"slug":"organismo_que_otorgo_la_beca","name":"Organismos que otorgan las becas"},"tipo_de_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/tipo_de_beca\/doctoral\/\" class=\"advgb-post-tax-term\">Doctoral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Doctoral<\/span>"],"slug":"tipo_de_beca","name":"Tipos de beca"},"unidad_academica":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/unidad_academica\/facultad-de-ciencias-naturales-y-museo\/\" class=\"advgb-post-tax-term\">FACULTAD DE CIENCIAS NATURALES Y MUSEO<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">FACULTAD DE CIENCIAS NATURALES Y MUSEO<\/span>"],"slug":"unidad_academica","name":"Unidades acad\u00e9micas"},"area_de_conocimiento":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/area_de_conocimiento\/cs-agricolas-y-biologicas\/\" class=\"advgb-post-tax-term\">Cs. Agr\u00edcolas y Biol\u00f3gicas<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Cs. Agr\u00edcolas y Biol\u00f3gicas<\/span>"],"slug":"area_de_conocimiento","name":"\u00c1reas de conocimiento"}},"series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie\/2556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/types\/becarie"}],"wp:attachment":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/media?parent=2556"}],"wp:term":[{"taxonomy":"palabras_claves","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves?post=2556"},{"taxonomy":"keywords","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords?post=2556"},{"taxonomy":"organismo_que_otorgo_la_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/organismo_que_otorgo_la_beca?post=2556"},{"taxonomy":"tipo_de_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/tipo_de_beca?post=2556"},{"taxonomy":"unidad_academica","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/unidad_academica?post=2556"},{"taxonomy":"area_de_conocimiento","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/area_de_conocimiento?post=2556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}