{"id":2038,"date":"2020-11-05T22:09:16","date_gmt":"2020-11-06T01:09:16","guid":{"rendered":"http:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/manuela-cerimelo\/?lang=es"},"modified":"2020-11-11T18:48:27","modified_gmt":"2020-11-11T21:48:27","slug":"manuela-cerimelo","status":"publish","type":"becarie","link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/becarie\/manuela-cerimelo\/","title":{"rendered":"Manuela Cerimelo"},"author":2,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"palabras_claves":[523,524,525,196],"keywords":[526,527,528,199],"organismo_que_otorgo_la_beca":[261],"tipo_de_beca":[36],"unidad_academica":[529],"area_de_conocimiento":[2324,2323],"class_list":["post-2038","becarie","type-becarie","status-publish","hentry","palabras_claves-egc","palabras_claves-empleo","palabras_claves-ingreso","palabras_claves-turismo","keywords-cge","keywords-employment","keywords-income","keywords-tourism","organismo_que_otorgo_la_beca-agencia","tipo_de_beca-doctoral","unidad_academica-facultad-de-ciencias-economicas","area_de_conocimiento-econometria-y-finanzas","area_de_conocimiento-economia","post"],"aioseo_notices":[],"acf":[],"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/author\/congresos\/","display_name":"congresos"},"relative_dates":{"created":"Posted 6 years ago","modified":"Updated 6 years ago"},"absolute_dates":{"created":"Posted on ","modified":"Updated on "},"absolute_dates_time":{"created":"Posted on  10:09 pm","modified":"Updated on  6:48 pm"},"featured_img_caption":"","tax_additional":{"palabras_claves":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/egc\/\" class=\"advgb-post-tax-term\">EGC<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/empleo\/\" class=\"advgb-post-tax-term\">EMPLEO<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/ingreso\/\" class=\"advgb-post-tax-term\">INGRESO<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/palabras_claves\/turismo\/\" class=\"advgb-post-tax-term\">TURISMO<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">EGC<\/span>","<span class=\"advgb-post-tax-term\">EMPLEO<\/span>","<span class=\"advgb-post-tax-term\">INGRESO<\/span>","<span class=\"advgb-post-tax-term\">TURISMO<\/span>"],"slug":"palabras_claves","name":"Palabras claves"},"keywords":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/cge\/\" class=\"advgb-post-tax-term\">CGE<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/employment\/\" class=\"advgb-post-tax-term\">EMPLOYMENT<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/income\/\" class=\"advgb-post-tax-term\">INCOME<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/keywords\/tourism\/\" class=\"advgb-post-tax-term\">TOURISM<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">CGE<\/span>","<span class=\"advgb-post-tax-term\">EMPLOYMENT<\/span>","<span class=\"advgb-post-tax-term\">INCOME<\/span>","<span class=\"advgb-post-tax-term\">TOURISM<\/span>"],"slug":"keywords","name":"Keywords"},"organismo_que_otorgo_la_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/organismo_que_otorgo_la_beca\/agencia\/\" class=\"advgb-post-tax-term\">AGENCIA<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">AGENCIA<\/span>"],"slug":"organismo_que_otorgo_la_beca","name":"Organismos que otorgan las becas"},"tipo_de_beca":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/tipo_de_beca\/doctoral\/\" class=\"advgb-post-tax-term\">Doctoral<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Doctoral<\/span>"],"slug":"tipo_de_beca","name":"Tipos de beca"},"unidad_academica":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/unidad_academica\/facultad-de-ciencias-economicas\/\" class=\"advgb-post-tax-term\">FACULTAD DE CIENCIAS ECON\u00d3MICAS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">FACULTAD DE CIENCIAS ECON\u00d3MICAS<\/span>"],"slug":"unidad_academica","name":"Unidades acad\u00e9micas"},"area_de_conocimiento":{"linked":["<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/area_de_conocimiento\/econometria-y-finanzas\/\" class=\"advgb-post-tax-term\">Econometr\u00eda y Finanzas<\/a>","<a href=\"https:\/\/congresos.unlp.edu.ar\/ebec2020\/area_de_conocimiento\/economia\/\" class=\"advgb-post-tax-term\">Econom\u00eda<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Econometr\u00eda y Finanzas<\/span>","<span class=\"advgb-post-tax-term\">Econom\u00eda<\/span>"],"slug":"area_de_conocimiento","name":"\u00c1reas de conocimiento"}},"series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie\/2038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/becarie"}],"about":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/types\/becarie"}],"wp:attachment":[{"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/media?parent=2038"}],"wp:term":[{"taxonomy":"palabras_claves","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/palabras_claves?post=2038"},{"taxonomy":"keywords","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/keywords?post=2038"},{"taxonomy":"organismo_que_otorgo_la_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/organismo_que_otorgo_la_beca?post=2038"},{"taxonomy":"tipo_de_beca","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/tipo_de_beca?post=2038"},{"taxonomy":"unidad_academica","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/unidad_academica?post=2038"},{"taxonomy":"area_de_conocimiento","embeddable":true,"href":"https:\/\/congresos.unlp.edu.ar\/ebec2020\/wp-json\/wp\/v2\/area_de_conocimiento?post=2038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}